{"id":77,"date":"2019-10-23T13:30:00","date_gmt":"2019-10-23T16:30:00","guid":{"rendered":"https:\/\/www.dooca.com.br\/blog\/?p=77"},"modified":"2021-05-05T11:25:08","modified_gmt":"2021-05-05T14:25:08","slug":"black-friday-compre-online-e-retire-na-loja-fisica","status":"publish","type":"post","link":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/","title":{"rendered":"Black Friday &#8211; compre online e retire na loja f\u00edsica"},"content":{"rendered":"\n<p>Estudo do Google aponta aumento de inten\u00e7\u00e3o de compra em lojas online e lojas f\u00edsicas durante a Black Friday de 2019, e mostra que 76% dos consumidores entrevistados entendem que o evento \u00e9 maior do que apenas a \u00faltima sexta-feira do m\u00eas de novembro.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/dooca.com.br\/files\/files\/black-friday-retire-loja.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>No Brasil, a Black Friday iniciou em 2010 \u00e9 tratada pelo segmento de e-commerce como o principal evento do ano. \u201cA grande maioria dos Brasileiros entendem que \u00e9 a semana de segunda a segunda\u201d, destaca Diego Venturelli, gerente de insights para o Varejo do Google Brasil.<\/p>\n\n\n\n<p>Segundo o Google, 39% dos consumidores Brasileiros consideram que a funcionalidade de \u201cretire na loja\u201d dispon\u00edvel na loja virtual, como muito importante na hora de decidir a sua compra na Black Friday e 24% esperam usar esta forma de entrega para as compras feitas online na edi\u00e7\u00e3o de 2019.<\/p>\n\n\n\n<p>A escolha da modalidade de entrega \u201cretire em loja\u201d \u00e9 impulsionada pela possibilidade de economia de frete e o imediatismo em receber a compra, o que corrobora tamb\u00e9m com o aumento de 75% na pesquisa dos consumidores de \u201clojas pr\u00f3ximas a mim\u201d nos \u00faltimos anos.<\/p>\n\n\n\n<p>Dos produtos com inten\u00e7\u00e3o de compra para 2019, destacam-se as seguintes categorias: celulares, computadores, eletros, roupas, cal\u00e7ados esportivos e perfumes. As vendas no e-commerce foram de Black Friday de 2018 movimentou R$ 2,6 bilh\u00f5es na Black Friday 2018, alta de 23% em rela\u00e7\u00e3o a 2017, aponta a Ebit|Nielsen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja como a estrat\u00e9gia de \u201cretire na loja\u201d pode aumentar os resultados da sua loja virtual na Black Friday 2019<\/p>\n","protected":false},"author":2,"featured_media":79,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,19],"tags":[45,46],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog\" \/>\n<meta property=\"og:description\" content=\"Veja como a estrat\u00e9gia de \u201cretire na loja\u201d pode aumentar os resultados da sua loja virtual na Black Friday 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\" \/>\n<meta property=\"og:site_name\" content=\"Dooca Commerce Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/dooca.commerce?_rdc=1&amp;amp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3b_rdr\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-23T16:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-05T14:25:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/artem-beliaikin-cE8cwN2A2-c-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hellenn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hellenn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\"},\"author\":{\"name\":\"Hellenn\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/50d256cab1d738cefcbb07183027d9ea\"},\"headline\":\"Black Friday &#8211; compre online e retire na loja f\u00edsica\",\"datePublished\":\"2019-10-23T16:30:00+00:00\",\"dateModified\":\"2021-05-05T14:25:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#organization\"},\"keywords\":[\"black friday\",\"retire na loja\"],\"articleSection\":[\"Loja virtual\",\"Marketing\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\",\"url\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\",\"name\":\"Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#website\"},\"datePublished\":\"2019-10-23T16:30:00+00:00\",\"dateModified\":\"2021-05-05T14:25:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dooca.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Black Friday &#8211; compre online e retire na loja f\u00edsica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#website\",\"url\":\"https:\/\/www.dooca.com.br\/blog\/\",\"name\":\"Dooca Commerce Blog\",\"description\":\"Not\u00edcias, v\u00eddeos e e-books gratuitos sobre o universo de lojas virtuais.\",\"publisher\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dooca.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#organization\",\"name\":\"Dooca Commerce\",\"url\":\"https:\/\/www.dooca.com.br\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/dooca.commerce\/\",\"https:\/\/br.linkedin.com\/company\/doocacommerce\",\"https:\/\/www.youtube.com\/channel\/UCCGBsQEj03aMqyVXTFwnjMw\",\"https:\/\/web.facebook.com\/dooca.commerce?_rdc=1&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;_rdr\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/cropped-fb_icon.png\",\"contentUrl\":\"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/cropped-fb_icon.png\",\"width\":512,\"height\":512,\"caption\":\"Dooca Commerce\"},\"image\":{\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/50d256cab1d738cefcbb07183027d9ea\",\"name\":\"Hellenn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca8ad86af49dc06571e533e5f9f94c0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca8ad86af49dc06571e533e5f9f94c0c?s=96&d=mm&r=g\",\"caption\":\"Hellenn\"},\"url\":\"https:\/\/www.dooca.com.br\/blog\/author\/hellenn-rech\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/","og_locale":"pt_BR","og_type":"article","og_title":"Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog","og_description":"Veja como a estrat\u00e9gia de \u201cretire na loja\u201d pode aumentar os resultados da sua loja virtual na Black Friday 2019","og_url":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/","og_site_name":"Dooca Commerce Blog","article_publisher":"https:\/\/web.facebook.com\/dooca.commerce?_rdc=1&amp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3bamp%3b_rdr","article_published_time":"2019-10-23T16:30:00+00:00","article_modified_time":"2021-05-05T14:25:08+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/artem-beliaikin-cE8cwN2A2-c-unsplash.jpg","type":"image\/jpeg"}],"author":"Hellenn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hellenn","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#article","isPartOf":{"@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/"},"author":{"name":"Hellenn","@id":"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/50d256cab1d738cefcbb07183027d9ea"},"headline":"Black Friday &#8211; compre online e retire na loja f\u00edsica","datePublished":"2019-10-23T16:30:00+00:00","dateModified":"2021-05-05T14:25:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/www.dooca.com.br\/blog\/#organization"},"keywords":["black friday","retire na loja"],"articleSection":["Loja virtual","Marketing"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/","url":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/","name":"Black Friday - compre online e retire na loja f\u00edsica - Dooca Commerce Blog","isPartOf":{"@id":"https:\/\/www.dooca.com.br\/blog\/#website"},"datePublished":"2019-10-23T16:30:00+00:00","dateModified":"2021-05-05T14:25:08+00:00","breadcrumb":{"@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dooca.com.br\/blog\/black-friday-compre-online-e-retire-na-loja-fisica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dooca.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Black Friday &#8211; compre online e retire na loja f\u00edsica"}]},{"@type":"WebSite","@id":"https:\/\/www.dooca.com.br\/blog\/#website","url":"https:\/\/www.dooca.com.br\/blog\/","name":"Dooca Commerce Blog","description":"Not\u00edcias, v\u00eddeos e e-books gratuitos sobre o universo de lojas virtuais.","publisher":{"@id":"https:\/\/www.dooca.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dooca.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.dooca.com.br\/blog\/#organization","name":"Dooca Commerce","url":"https:\/\/www.dooca.com.br\/blog\/","sameAs":["https:\/\/www.instagram.com\/dooca.commerce\/","https:\/\/br.linkedin.com\/company\/doocacommerce","https:\/\/www.youtube.com\/channel\/UCCGBsQEj03aMqyVXTFwnjMw","https:\/\/web.facebook.com\/dooca.commerce?_rdc=1&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;_rdr"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.dooca.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/cropped-fb_icon.png","contentUrl":"https:\/\/www.dooca.com.br\/blog\/wp-content\/uploads\/2021\/05\/cropped-fb_icon.png","width":512,"height":512,"caption":"Dooca Commerce"},"image":{"@id":"https:\/\/www.dooca.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/50d256cab1d738cefcbb07183027d9ea","name":"Hellenn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.dooca.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca8ad86af49dc06571e533e5f9f94c0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca8ad86af49dc06571e533e5f9f94c0c?s=96&d=mm&r=g","caption":"Hellenn"},"url":"https:\/\/www.dooca.com.br\/blog\/author\/hellenn-rech\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/posts\/77"}],"collection":[{"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":1,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/posts\/77\/revisions"}],"predecessor-version":[{"id":80,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/posts\/77\/revisions\/80"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/media\/79"}],"wp:attachment":[{"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/media?parent=77"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/categories?post=77"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dooca.com.br\/blog\/wp-json\/wp\/v2\/tags?post=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}